{"id":8050,"count":1,"description":"","link":"https:\/\/iliverpool.info\/en\/tag\/liverpool-etiquette","name":"Liverpool etiquette","slug":"liverpool-etiquette","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/tags\/8050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/posts?tags=8050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}