{"id":8057,"count":1,"description":"","link":"https:\/\/iliverpool.info\/en\/tag\/liverpool-local-traditions","name":"Liverpool local traditions","slug":"liverpool-local-traditions","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/tags\/8057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/iliverpool.info\/en\/wp-json\/wp\/v2\/posts?tags=8057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}