{"id":4948,"count":1,"description":"","link":"https:\/\/iliverpool.info\/ru\/tag\/%d0%b8%d1%81%d1%82%d0%be%d1%80%d0%b8%d1%8f-%d1%80%d0%b0%d0%b7%d0%b2%d0%b8%d1%82%d0%b8%d1%8f-%d0%bb%d0%b8%d0%b2%d0%b5%d1%80%d0%bf%d1%83%d0%bb%d1%8c%d1%81%d0%ba%d0%be%d0%b3%d0%be-%d0%b0%d1%8d%d1%80","name":"\u0418\u0441\u0442\u043e\u0440\u0438\u044f \u0440\u0430\u0437\u0432\u0438\u0442\u0438\u044f \u041b\u0438\u0432\u0435\u0440\u043f\u0443\u043b\u044c\u0441\u043a\u043e\u0433\u043e \u0430\u044d\u0440\u043e\u043f\u043e\u0440\u0442\u0430 \u0438\u043c\u0435\u043d\u0438 \u0414\u0436\u043e\u043d\u0430 \u041b\u0435\u043d\u043d\u043e\u043d\u0430","slug":"%d0%b8%d1%81%d1%82%d0%be%d1%80%d0%b8%d1%8f-%d1%80%d0%b0%d0%b7%d0%b2%d0%b8%d1%82%d0%b8%d1%8f-%d0%bb%d0%b8%d0%b2%d0%b5%d1%80%d0%bf%d1%83%d0%bb%d1%8c%d1%81%d0%ba%d0%be%d0%b3%d0%be-%d0%b0%d1%8d%d1%80","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/tags\/4948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/posts?tags=4948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}