{"id":5886,"count":1,"description":"","link":"https:\/\/iliverpool.info\/ru\/t-clatterbridge-general-hospital","name":"Clatterbridge General Hospital","slug":"clatterbridge-general-hospital","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/tags\/5886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/iliverpool.info\/ru\/wp-json\/wp\/v2\/posts?tags=5886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}